{"id":38702,"date":"2025-12-01T08:58:01","date_gmt":"2025-12-01T07:58:01","guid":{"rendered":"https:\/\/www.alteacultural.com\/events\/expo-luces-y-sombras\/"},"modified":"2025-12-18T09:51:40","modified_gmt":"2025-12-18T08:51:40","slug":"expo-luces-y-sombras","status":"publish","type":"mec-events","link":"https:\/\/www.alteacultural.com\/es\/events\/expo-luces-y-sombras\/","title":{"rendered":"Expo: Luces y Sombras"},"content":{"rendered":"<p>4-dic a 10-ene | Fundaci\u00f3n Schlotter<\/p>\n<p>Exposici\u00f3n: Luces y Sombras.<\/p>\n<p>Inauguraci\u00f3n: 4 de diciembre a las 18:00 h.<\/p>\n<p>Entrada libre y gratuita.<\/p>\n<p>Horario de visitas: Martes a s\u00e1bado de 10:30 a 13:30 h y 17:00 a 20:00 h.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-38698\" src=\"https:\/\/www.alteacultural.com\/wp-content\/uploads\/2025\/12\/ExpoLucesSombrasAltea_4dic_a_10ene_Cartel-A3_page-0001-scaled.jpg\" alt=\"\" width=\"750\" height=\"1061\" srcset=\"https:\/\/www.alteacultural.com\/wp-content\/uploads\/2025\/12\/ExpoLucesSombrasAltea_4dic_a_10ene_Cartel-A3_page-0001-scaled.jpg 1810w, https:\/\/www.alteacultural.com\/wp-content\/uploads\/2025\/12\/ExpoLucesSombrasAltea_4dic_a_10ene_Cartel-A3_page-0001-768x1086.jpg 768w, https:\/\/www.alteacultural.com\/wp-content\/uploads\/2025\/12\/ExpoLucesSombrasAltea_4dic_a_10ene_Cartel-A3_page-0001-1086x1536.jpg 1086w, https:\/\/www.alteacultural.com\/wp-content\/uploads\/2025\/12\/ExpoLucesSombrasAltea_4dic_a_10ene_Cartel-A3_page-0001-1448x2048.jpg 1448w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>4-dic a 10-ene | Fundaci\u00f3n Schlotter Exposici\u00f3n: Luces y Sombras. Inauguraci\u00f3n: 4 de diciembre a las 18:00 h. Entrada [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":38701,"comment_status":"open","ping_status":"closed","template":"","meta":{"_expiration-date-status":"","_expiration-date":0,"_expiration-date-type":"","_expiration-date-categories":[],"_expiration-date-options":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Expo: Luces y Sombras - Altea Cultural<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alteacultural.com\/es\/events\/expo-luces-y-sombras\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Expo: Luces y Sombras - Altea Cultural\" \/>\n<meta property=\"og:description\" content=\"4-dic a 10-ene | Fundaci\u00f3n Schlotter Exposici\u00f3n: Luces y Sombras. Inauguraci\u00f3n: 4 de diciembre a las 18:00 h. Entrada [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alteacultural.com\/es\/events\/expo-luces-y-sombras\/\" \/>\n<meta property=\"og:site_name\" content=\"Altea Cultural\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-18T08:51:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.alteacultural.com\/wp-content\/uploads\/2025\/12\/2025-12-04_LucesYSombras_banner-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1624\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.alteacultural.com\/es\/events\/expo-luces-y-sombras\/\",\"url\":\"https:\/\/www.alteacultural.com\/es\/events\/expo-luces-y-sombras\/\",\"name\":\"Expo: Luces y Sombras - Altea Cultural\",\"isPartOf\":{\"@id\":\"https:\/\/www.alteacultural.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.alteacultural.com\/es\/events\/expo-luces-y-sombras\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.alteacultural.com\/es\/events\/expo-luces-y-sombras\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.alteacultural.com\/wp-content\/uploads\/2025\/12\/2025-12-04_LucesYSombras_banner-scaled.jpg\",\"datePublished\":\"2025-12-01T07:58:01+00:00\",\"dateModified\":\"2025-12-18T08:51:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.alteacultural.com\/es\/events\/expo-luces-y-sombras\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.alteacultural.com\/es\/events\/expo-luces-y-sombras\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.alteacultural.com\/es\/events\/expo-luces-y-sombras\/#primaryimage\",\"url\":\"https:\/\/www.alteacultural.com\/wp-content\/uploads\/2025\/12\/2025-12-04_LucesYSombras_banner-scaled.jpg\",\"contentUrl\":\"https:\/\/www.alteacultural.com\/wp-content\/uploads\/2025\/12\/2025-12-04_LucesYSombras_banner-scaled.jpg\",\"width\":2560,\"height\":1624},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.alteacultural.com\/es\/events\/expo-luces-y-sombras\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/www.alteacultural.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\/\/www.alteacultural.com\/es\/events\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Expo: Luces y Sombras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.alteacultural.com\/es\/#website\",\"url\":\"https:\/\/www.alteacultural.com\/es\/\",\"name\":\"Altea Cultural\",\"description\":\"Regidoria de Cultura de l&#039;Ajuntament d&#039;Altea\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.alteacultural.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Expo: Luces y Sombras - Altea Cultural","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alteacultural.com\/es\/events\/expo-luces-y-sombras\/","og_locale":"es_ES","og_type":"article","og_title":"Expo: Luces y Sombras - Altea Cultural","og_description":"4-dic a 10-ene | Fundaci\u00f3n Schlotter Exposici\u00f3n: Luces y Sombras. Inauguraci\u00f3n: 4 de diciembre a las 18:00 h. Entrada [&hellip;]","og_url":"https:\/\/www.alteacultural.com\/es\/events\/expo-luces-y-sombras\/","og_site_name":"Altea Cultural","article_modified_time":"2025-12-18T08:51:40+00:00","og_image":[{"width":2560,"height":1624,"url":"https:\/\/www.alteacultural.com\/wp-content\/uploads\/2025\/12\/2025-12-04_LucesYSombras_banner-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.alteacultural.com\/es\/events\/expo-luces-y-sombras\/","url":"https:\/\/www.alteacultural.com\/es\/events\/expo-luces-y-sombras\/","name":"Expo: Luces y Sombras - Altea Cultural","isPartOf":{"@id":"https:\/\/www.alteacultural.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.alteacultural.com\/es\/events\/expo-luces-y-sombras\/#primaryimage"},"image":{"@id":"https:\/\/www.alteacultural.com\/es\/events\/expo-luces-y-sombras\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alteacultural.com\/wp-content\/uploads\/2025\/12\/2025-12-04_LucesYSombras_banner-scaled.jpg","datePublished":"2025-12-01T07:58:01+00:00","dateModified":"2025-12-18T08:51:40+00:00","breadcrumb":{"@id":"https:\/\/www.alteacultural.com\/es\/events\/expo-luces-y-sombras\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alteacultural.com\/es\/events\/expo-luces-y-sombras\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.alteacultural.com\/es\/events\/expo-luces-y-sombras\/#primaryimage","url":"https:\/\/www.alteacultural.com\/wp-content\/uploads\/2025\/12\/2025-12-04_LucesYSombras_banner-scaled.jpg","contentUrl":"https:\/\/www.alteacultural.com\/wp-content\/uploads\/2025\/12\/2025-12-04_LucesYSombras_banner-scaled.jpg","width":2560,"height":1624},{"@type":"BreadcrumbList","@id":"https:\/\/www.alteacultural.com\/es\/events\/expo-luces-y-sombras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.alteacultural.com\/es\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/www.alteacultural.com\/es\/events\/"},{"@type":"ListItem","position":3,"name":"Expo: Luces y Sombras"}]},{"@type":"WebSite","@id":"https:\/\/www.alteacultural.com\/es\/#website","url":"https:\/\/www.alteacultural.com\/es\/","name":"Altea Cultural","description":"Regidoria de Cultura de l&#039;Ajuntament d&#039;Altea","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alteacultural.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"mec_cost":"Entrada libre y gratuita","mec_date":{"start":{"date":"2025-12-04","hour":6,"minutes":"0","ampm":"PM"},"end":{"date":"2026-01-10","hour":8,"minutes":"0","ampm":"PM"},"hide_time":"1","hide_end_time":"1","comment":"","repeat":{"type":"daily","interval":"1","advanced":"","end":"never","end_at_date":"","end_at_occurrences":"10"}},"_links":{"self":[{"href":"https:\/\/www.alteacultural.com\/es\/wp-json\/wp\/v2\/mec-events\/38702"}],"collection":[{"href":"https:\/\/www.alteacultural.com\/es\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/www.alteacultural.com\/es\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/www.alteacultural.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alteacultural.com\/es\/wp-json\/wp\/v2\/comments?post=38702"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alteacultural.com\/es\/wp-json\/wp\/v2\/media\/38701"}],"wp:attachment":[{"href":"https:\/\/www.alteacultural.com\/es\/wp-json\/wp\/v2\/media?parent=38702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}