{"id":40441,"date":"2026-05-04T20:12:09","date_gmt":"2026-05-04T18:12:09","guid":{"rendered":"https:\/\/www.alteacultural.com\/events\/narracio-de-diversos-contes-20-de-maig-encontes-2026\/"},"modified":"2026-05-04T22:18:54","modified_gmt":"2026-05-04T20:18:54","slug":"narracio-de-diversos-contes-20-de-maig-encontes-2026","status":"publish","type":"mec-events","link":"https:\/\/www.alteacultural.com\/es\/events\/narracio-de-diversos-contes-20-de-maig-encontes-2026\/","title":{"rendered":"Narraci\u00f3n de varios cuentos 20 de mayo \u2013 Encontes 2026"},"content":{"rendered":"<p>20-may | Altea<\/p>\n<p><strong>Festival de Narraci\u00f3n Oral de Altea 2026<\/strong><\/p>\n<p><strong>9:30 h. \u00abCuentos a mano\u00bb.<\/strong> Peque\u00f1o homenaje a Jaime I en el 750 cumplea\u00f1os de su muerte. Alumnos Colegio Altea la Vella.<\/p>\n<p>Plaza de la iglesia de Altea la Vella.<\/p>\n<p><strong>12:00 h. \u00abCuentos a mano\u00bb<\/strong>. Peque\u00f1o homenaje a Jaime I en el 750 cumplea\u00f1os de su muerte. Alumnos Colegio la Olla.<\/p>\n<p>Villa Gadea.<\/p>\n<p>Cuentacuentos a cargo de Vicent Cort\u00e9s.<\/p>\n<p>Narraci\u00f3n en valenciano.<\/p>\n<p>Con la colaboraci\u00f3n de la Fundaci\u00f3n Bromera para el Fomento de la Lectura.<\/p>\n<p><a href=\"https:\/\/www.alteacultural.com\/encontes\/\">Tota la programaci\u00f3 ac\u00ed \/ Toda la programaci\u00f3n aqu\u00ed<\/a><\/p>\n<p><strong>18.\u00ba Mercado de Intercambio de Libros de Cuentos<\/strong>. \u00abCuentos que alimentan\u00bb. Intercambio de libros de cuentos por alimentos. Lleva un kg de alimentos que no sean frescos ni refrigerados y ll\u00e9vate un libro.<\/p>\n<p>Lugar: Casa de Cultura. Todos los d\u00edas en el horario habitual.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-40414\" src=\"https:\/\/www.alteacultural.com\/wp-content\/uploads\/2026\/05\/2026-05-21-EncontesAltea2026_cartell-scaled.jpg\" alt=\"\" width=\"750\" height=\"1061\" srcset=\"https:\/\/www.alteacultural.com\/wp-content\/uploads\/2026\/05\/2026-05-21-EncontesAltea2026_cartell-scaled.jpg 1810w, https:\/\/www.alteacultural.com\/wp-content\/uploads\/2026\/05\/2026-05-21-EncontesAltea2026_cartell-768x1086.jpg 768w, https:\/\/www.alteacultural.com\/wp-content\/uploads\/2026\/05\/2026-05-21-EncontesAltea2026_cartell-1086x1536.jpg 1086w, https:\/\/www.alteacultural.com\/wp-content\/uploads\/2026\/05\/2026-05-21-EncontesAltea2026_cartell-1448x2048.jpg 1448w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>20-may | Altea Festival de Narraci\u00f3n Oral de Altea 2026 9:30 h. \u00abCuentos a mano\u00bb. Peque\u00f1o homenaje a Jaime [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":40384,"comment_status":"open","ping_status":"closed","template":"","meta":{"_expiration-date-status":"","_expiration-date":0,"_expiration-date-type":"","_expiration-date-categories":[],"_expiration-date-options":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Narraci\u00f3n de varios cuentos 20 de mayo \u2013 Encontes 2026 - Altea Cultural<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alteacultural.com\/es\/events\/narracio-de-diversos-contes-20-de-maig-encontes-2026\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Narraci\u00f3n de varios cuentos 20 de mayo \u2013 Encontes 2026 - Altea Cultural\" \/>\n<meta property=\"og:description\" content=\"20-may | Altea Festival de Narraci\u00f3n Oral de Altea 2026 9:30 h. \u00abCuentos a mano\u00bb. Peque\u00f1o homenaje a Jaime [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alteacultural.com\/es\/events\/narracio-de-diversos-contes-20-de-maig-encontes-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Altea Cultural\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T20:18:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.alteacultural.com\/wp-content\/uploads\/2026\/05\/EncontesAltea2026_benner.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1120\" \/>\n\t<meta property=\"og:image:height\" content=\"458\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.alteacultural.com\/es\/events\/narracio-de-diversos-contes-20-de-maig-encontes-2026\/\",\"url\":\"https:\/\/www.alteacultural.com\/es\/events\/narracio-de-diversos-contes-20-de-maig-encontes-2026\/\",\"name\":\"Narraci\u00f3n de varios cuentos 20 de mayo \u2013 Encontes 2026 - Altea Cultural\",\"isPartOf\":{\"@id\":\"https:\/\/www.alteacultural.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.alteacultural.com\/es\/events\/narracio-de-diversos-contes-20-de-maig-encontes-2026\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.alteacultural.com\/es\/events\/narracio-de-diversos-contes-20-de-maig-encontes-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.alteacultural.com\/wp-content\/uploads\/2026\/05\/EncontesAltea2026_benner.jpg\",\"datePublished\":\"2026-05-04T18:12:09+00:00\",\"dateModified\":\"2026-05-04T20:18:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.alteacultural.com\/es\/events\/narracio-de-diversos-contes-20-de-maig-encontes-2026\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.alteacultural.com\/es\/events\/narracio-de-diversos-contes-20-de-maig-encontes-2026\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.alteacultural.com\/es\/events\/narracio-de-diversos-contes-20-de-maig-encontes-2026\/#primaryimage\",\"url\":\"https:\/\/www.alteacultural.com\/wp-content\/uploads\/2026\/05\/EncontesAltea2026_benner.jpg\",\"contentUrl\":\"https:\/\/www.alteacultural.com\/wp-content\/uploads\/2026\/05\/EncontesAltea2026_benner.jpg\",\"width\":1120,\"height\":458},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.alteacultural.com\/es\/events\/narracio-de-diversos-contes-20-de-maig-encontes-2026\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/www.alteacultural.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\/\/www.alteacultural.com\/es\/events\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Narraci\u00f3n de varios cuentos 20 de mayo \u2013 Encontes 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.alteacultural.com\/es\/#website\",\"url\":\"https:\/\/www.alteacultural.com\/es\/\",\"name\":\"Altea Cultural\",\"description\":\"Regidoria de Cultura de l&#039;Ajuntament d&#039;Altea\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.alteacultural.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Narraci\u00f3n de varios cuentos 20 de mayo \u2013 Encontes 2026 - Altea Cultural","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alteacultural.com\/es\/events\/narracio-de-diversos-contes-20-de-maig-encontes-2026\/","og_locale":"es_ES","og_type":"article","og_title":"Narraci\u00f3n de varios cuentos 20 de mayo \u2013 Encontes 2026 - Altea Cultural","og_description":"20-may | Altea Festival de Narraci\u00f3n Oral de Altea 2026 9:30 h. \u00abCuentos a mano\u00bb. Peque\u00f1o homenaje a Jaime [&hellip;]","og_url":"https:\/\/www.alteacultural.com\/es\/events\/narracio-de-diversos-contes-20-de-maig-encontes-2026\/","og_site_name":"Altea Cultural","article_modified_time":"2026-05-04T20:18:54+00:00","og_image":[{"width":1120,"height":458,"url":"https:\/\/www.alteacultural.com\/wp-content\/uploads\/2026\/05\/EncontesAltea2026_benner.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.alteacultural.com\/es\/events\/narracio-de-diversos-contes-20-de-maig-encontes-2026\/","url":"https:\/\/www.alteacultural.com\/es\/events\/narracio-de-diversos-contes-20-de-maig-encontes-2026\/","name":"Narraci\u00f3n de varios cuentos 20 de mayo \u2013 Encontes 2026 - Altea Cultural","isPartOf":{"@id":"https:\/\/www.alteacultural.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.alteacultural.com\/es\/events\/narracio-de-diversos-contes-20-de-maig-encontes-2026\/#primaryimage"},"image":{"@id":"https:\/\/www.alteacultural.com\/es\/events\/narracio-de-diversos-contes-20-de-maig-encontes-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alteacultural.com\/wp-content\/uploads\/2026\/05\/EncontesAltea2026_benner.jpg","datePublished":"2026-05-04T18:12:09+00:00","dateModified":"2026-05-04T20:18:54+00:00","breadcrumb":{"@id":"https:\/\/www.alteacultural.com\/es\/events\/narracio-de-diversos-contes-20-de-maig-encontes-2026\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alteacultural.com\/es\/events\/narracio-de-diversos-contes-20-de-maig-encontes-2026\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.alteacultural.com\/es\/events\/narracio-de-diversos-contes-20-de-maig-encontes-2026\/#primaryimage","url":"https:\/\/www.alteacultural.com\/wp-content\/uploads\/2026\/05\/EncontesAltea2026_benner.jpg","contentUrl":"https:\/\/www.alteacultural.com\/wp-content\/uploads\/2026\/05\/EncontesAltea2026_benner.jpg","width":1120,"height":458},{"@type":"BreadcrumbList","@id":"https:\/\/www.alteacultural.com\/es\/events\/narracio-de-diversos-contes-20-de-maig-encontes-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.alteacultural.com\/es\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/www.alteacultural.com\/es\/events\/"},{"@type":"ListItem","position":3,"name":"Narraci\u00f3n de varios cuentos 20 de mayo \u2013 Encontes 2026"}]},{"@type":"WebSite","@id":"https:\/\/www.alteacultural.com\/es\/#website","url":"https:\/\/www.alteacultural.com\/es\/","name":"Altea Cultural","description":"Regidoria de Cultura de l&#039;Ajuntament d&#039;Altea","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alteacultural.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"mec_cost":"Entrada libre y gratuita","mec_date":{"start":{"date":"2026-05-20","hour":"8","minutes":"0","ampm":"AM"},"end":{"date":"2026-05-20","hour":6,"minutes":"0","ampm":"PM"},"allday":"1","comment":"","repeat":{"type":"daily","interval":"1","advanced":"","end":"never","end_at_date":"","end_at_occurrences":"10"}},"_links":{"self":[{"href":"https:\/\/www.alteacultural.com\/es\/wp-json\/wp\/v2\/mec-events\/40441"}],"collection":[{"href":"https:\/\/www.alteacultural.com\/es\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/www.alteacultural.com\/es\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/www.alteacultural.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alteacultural.com\/es\/wp-json\/wp\/v2\/comments?post=40441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alteacultural.com\/es\/wp-json\/wp\/v2\/media\/40384"}],"wp:attachment":[{"href":"https:\/\/www.alteacultural.com\/es\/wp-json\/wp\/v2\/media?parent=40441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}